{"id":867,"date":"2025-03-11T17:23:13","date_gmt":"2025-03-11T15:23:13","guid":{"rendered":"https:\/\/www.ro.design\/product\/bare\/"},"modified":"2026-02-09T17:08:28","modified_gmt":"2026-02-09T15:08:28","slug":"bare","status":"publish","type":"product","link":"https:\/\/www.ro.design\/it\/prodotti\/bare\/","title":{"rendered":"Bare"},"content":{"rendered":"\n<!-- TITLES -->\n<div class=\"titles custom-block\" >\n    <h1>Bare<\/h1>\n<\/div>\n\n\n<!-- SECTION HERO PAGE STANDARD -->\n\n<!-- SECTION HERO PAGE STANDARD -->\n    <div id=\"gallery_6a04799060367\" class=\"gallery-slider\">\n                                <div class=\"gallery-slider--item\">\n                        <a href=\"https:\/\/www.ro.design\/wp-content\/uploads\/2025\/03\/bare3.webp\"\n                        data-gallery=\"gallery_6a04799060367\"\n                        data-description=\"\">\n                    <img decoding=\"async\" class=\"lazy\" src=\"https:\/\/www.ro.design\/wp-content\/uploads\/2025\/03\/bare3.webp\"\n                         alt=\"\" \/>\n                <\/a>\n            <\/div>\n                                            <div class=\"gallery-slider--item\">\n                        <a href=\"https:\/\/www.ro.design\/wp-content\/uploads\/2025\/03\/bare1.webp\"\n                        data-gallery=\"gallery_6a04799060367\"\n                        data-description=\"\">\n                    <img decoding=\"async\" class=\"lazy\" src=\"https:\/\/www.ro.design\/wp-content\/uploads\/2025\/03\/bare1.webp\"\n                         alt=\"\" \/>\n                <\/a>\n            <\/div>\n                                            <div class=\"gallery-slider--item\">\n                        <a href=\"https:\/\/www.ro.design\/wp-content\/uploads\/2025\/03\/bare2.webp\"\n                        data-gallery=\"gallery_6a04799060367\"\n                        data-description=\"\">\n                    <img decoding=\"async\" class=\"lazy\" src=\"https:\/\/www.ro.design\/wp-content\/uploads\/2025\/03\/bare2.webp\"\n                         alt=\"\" \/>\n                <\/a>\n            <\/div>\n                                            <div class=\"gallery-slider--item\">\n                        <a href=\"https:\/\/www.ro.design\/wp-content\/uploads\/2025\/03\/bare4.webp\"\n                        data-gallery=\"gallery_6a04799060367\"\n                        data-description=\"\">\n                    <img decoding=\"async\" class=\"lazy\" src=\"https:\/\/www.ro.design\/wp-content\/uploads\/2025\/03\/bare4.webp\"\n                         alt=\"\" \/>\n                <\/a>\n            <\/div>\n                                            <div class=\"gallery-slider--item\">\n                        <a href=\"https:\/\/www.ro.design\/wp-content\/uploads\/2025\/03\/bare5.webp\"\n                        data-gallery=\"gallery_6a04799060367\"\n                        data-description=\"\">\n                    <img decoding=\"async\" class=\"lazy\" src=\"https:\/\/www.ro.design\/wp-content\/uploads\/2025\/03\/bare5.webp\"\n                         alt=\"\" \/>\n                <\/a>\n            <\/div>\n                        <\/div>\n\n\n\n<!-- SECTION columns text -->\n    <div class=\"columns-text\">\n                    <div class=\"columns-text--column\">\n                <section class=\"product-text observe white-section\">\n<section class=\"product-text observe white-section\">\n<div class=\"div-block-51\">\n<p>La collezione ricrea l\u2019effetto di un muro in mattoni antichi a vista. I segni del tempo e le stratificazioni di finiture assorbite nel corso degli anni sono ci\u00f2 che d\u00e0 origine alle texture uniche della serie Bare.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/section>\n<\/section>\n            <\/div>\n                    <div class=\"columns-text--column\">\n                <p class=\"product-paragraph\">\u00c8 una collezione interamente dedicata alla materia e alla texture: per questo viene proposta in un\u2019unica geometria e formato, declinata in un ricco mix di dieci pattern differenti.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><em>Designed by Betonada<\/em><\/strong><\/p>\n            <\/div>\n            <\/div>\n","protected":false},"featured_media":46,"template":"","meta":{"_acf_changed":true},"class_list":["post-867","product","type-product","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ro.design\/it\/wp-json\/wp\/v2\/product\/867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ro.design\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.ro.design\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ro.design\/it\/wp-json\/wp\/v2\/media\/46"}],"wp:attachment":[{"href":"https:\/\/www.ro.design\/it\/wp-json\/wp\/v2\/media?parent=867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}