{"id":859,"date":"2025-03-11T17:27:04","date_gmt":"2025-03-11T15:27:04","guid":{"rendered":"https:\/\/www.ro.design\/product\/quilt\/"},"modified":"2026-02-09T16:59:24","modified_gmt":"2026-02-09T14:59:24","slug":"quilt","status":"publish","type":"product","link":"https:\/\/www.ro.design\/it\/prodotti\/quilt\/","title":{"rendered":"Quilt"},"content":{"rendered":"\n<!-- TITLES -->\n<div class=\"titles custom-block\" >\n    <h1>Quilt<\/h1>\n<\/div>\n\n\n<!-- SECTION HERO PAGE STANDARD -->\n\n<!-- SECTION HERO PAGE STANDARD -->\n    <div id=\"gallery_6a0479ad69f1b\" class=\"gallery-slider\">\n                                <div class=\"gallery-slider--item\">\n                        <a href=\"https:\/\/www.ro.design\/wp-content\/uploads\/2025\/03\/quilt1.webp\"\n                        data-gallery=\"gallery_6a0479ad69f1b\"\n                        data-description=\"\">\n                    <img decoding=\"async\" class=\"lazy\" src=\"https:\/\/www.ro.design\/wp-content\/uploads\/2025\/03\/quilt1.webp\"\n                         alt=\"\" \/>\n                <\/a>\n            <\/div>\n                                            <div class=\"gallery-slider--item\">\n                        <a href=\"https:\/\/www.ro.design\/wp-content\/uploads\/2025\/03\/quilt2.webp\"\n                        data-gallery=\"gallery_6a0479ad69f1b\"\n                        data-description=\"\">\n                    <img decoding=\"async\" class=\"lazy\" src=\"https:\/\/www.ro.design\/wp-content\/uploads\/2025\/03\/quilt2.webp\"\n                         alt=\"\" \/>\n                <\/a>\n            <\/div>\n                                            <div class=\"gallery-slider--item\">\n                        <a href=\"https:\/\/www.ro.design\/wp-content\/uploads\/2025\/03\/quilt3.webp\"\n                        data-gallery=\"gallery_6a0479ad69f1b\"\n                        data-description=\"\">\n                    <img decoding=\"async\" class=\"lazy\" src=\"https:\/\/www.ro.design\/wp-content\/uploads\/2025\/03\/quilt3.webp\"\n                         alt=\"\" \/>\n                <\/a>\n            <\/div>\n                                            <div class=\"gallery-slider--item\">\n                        <a href=\"https:\/\/www.ro.design\/wp-content\/uploads\/2025\/03\/quilt4.webp\"\n                        data-gallery=\"gallery_6a0479ad69f1b\"\n                        data-description=\"\">\n                    <img decoding=\"async\" class=\"lazy\" src=\"https:\/\/www.ro.design\/wp-content\/uploads\/2025\/03\/quilt4.webp\"\n                         alt=\"\" \/>\n                <\/a>\n            <\/div>\n                                            <div class=\"gallery-slider--item\">\n                        <a href=\"https:\/\/www.ro.design\/wp-content\/uploads\/2025\/03\/quilt5.webp\"\n                        data-gallery=\"gallery_6a0479ad69f1b\"\n                        data-description=\"\">\n                    <img decoding=\"async\" class=\"lazy\" src=\"https:\/\/www.ro.design\/wp-content\/uploads\/2025\/03\/quilt5.webp\"\n                         alt=\"\" \/>\n                <\/a>\n            <\/div>\n                                            <div class=\"gallery-slider--item\">\n                        <a href=\"https:\/\/www.ro.design\/wp-content\/uploads\/2025\/03\/quilt6.webp\"\n                        data-gallery=\"gallery_6a0479ad69f1b\"\n                        data-description=\"\">\n                    <img decoding=\"async\" class=\"lazy\" src=\"https:\/\/www.ro.design\/wp-content\/uploads\/2025\/03\/quilt6.webp\"\n                         alt=\"\" \/>\n                <\/a>\n            <\/div>\n                                            <div class=\"gallery-slider--item\">\n                        <a href=\"https:\/\/www.ro.design\/wp-content\/uploads\/2025\/03\/quilt7.webp\"\n                        data-gallery=\"gallery_6a0479ad69f1b\"\n                        data-description=\"\">\n                    <img decoding=\"async\" class=\"lazy\" src=\"https:\/\/www.ro.design\/wp-content\/uploads\/2025\/03\/quilt7.webp\"\n                         alt=\"\" \/>\n                <\/a>\n            <\/div>\n                                            <div class=\"gallery-slider--item\">\n                        <a href=\"https:\/\/www.ro.design\/wp-content\/uploads\/2025\/03\/quilt8.webp\"\n                        data-gallery=\"gallery_6a0479ad69f1b\"\n                        data-description=\"\">\n                    <img decoding=\"async\" class=\"lazy\" src=\"https:\/\/www.ro.design\/wp-content\/uploads\/2025\/03\/quilt8.webp\"\n                         alt=\"\" \/>\n                <\/a>\n            <\/div>\n                                            <div class=\"gallery-slider--item\">\n                        <a href=\"https:\/\/www.ro.design\/wp-content\/uploads\/2025\/03\/quilt9.webp\"\n                        data-gallery=\"gallery_6a0479ad69f1b\"\n                        data-description=\"\">\n                    <img decoding=\"async\" class=\"lazy\" src=\"https:\/\/www.ro.design\/wp-content\/uploads\/2025\/03\/quilt9.webp\"\n                         alt=\"\" \/>\n                <\/a>\n            <\/div>\n                                            <div class=\"gallery-slider--item\">\n                        <a href=\"https:\/\/www.ro.design\/wp-content\/uploads\/2025\/03\/quilt10.webp\"\n                        data-gallery=\"gallery_6a0479ad69f1b\"\n                        data-description=\"\">\n                    <img decoding=\"async\" class=\"lazy\" src=\"https:\/\/www.ro.design\/wp-content\/uploads\/2025\/03\/quilt10.webp\"\n                         alt=\"\" \/>\n                <\/a>\n            <\/div>\n                        <\/div>\n\n\n\n<!-- SECTION columns text -->\n    <div class=\"columns-text\">\n                    <div class=\"columns-text--column\">\n                <section class=\"product-text observe white-section\">\n<section class=\"product-text observe white-section\">\n<section class=\"product-text observe white-section\">\n<div class=\"div-block-51\">\n<p>Infinite combinazioni. La serie Quilt \u00e8 una collezione particolarmente cara a RO. Integrando pizzi, incisioni delicate e suggestioni tessili, il team RO ha dato vita a un insieme di texture ricche e sofisticate. Apparentemente casuale ma accuratamente strutturato, il design si compone di otto diverse texture di superficie, trasformandosi in un elemento distintivo capace di caratterizzare qualsiasi spazio.<\/p>\n<\/div>\n<\/section>\n<\/section>\n<\/section>\n            <\/div>\n                    <div class=\"columns-text--column\">\n                <p>Quilt pu\u00f2 essere proposta come composizione standard, oppure le mattonelle possono essere combinate liberamente per rispondere alla visione di ogni progetto. L\u2019incontro tra texture nuove e richiami pi\u00f9 tradizionali d\u00e0 forma a piastrelle realizzate artigianalmente con estrema cura, adatte sia per ambienti interni che esterni. Utilizzabili su pareti e pavimenti, le Quilt Tiles sono disponibili in una palette di dieci colori.<\/p>\n            <\/div>\n            <\/div>\n\n\n\n<!-- SECTION columns text -->\n    <div class=\"columns-text\">\n                    <div class=\"columns-text--column\">\n                <section class=\"product-text observe white-section\">\n<section class=\"product-text observe white-section\">\n<section class=\"product-text observe white-section\">\n<div class=\"div-block-51\"><\/div>\n<div class=\"div-block-64\">\n<div class=\"text-block-14\"><em>Designed by Tali Edry<\/em><\/div>\n<\/div>\n<\/section>\n<\/section>\n<\/section>\n            <\/div>\n            <\/div>\n","protected":false},"featured_media":60,"template":"","meta":{"_acf_changed":true},"class_list":["post-859","product","type-product","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ro.design\/it\/wp-json\/wp\/v2\/product\/859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ro.design\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.ro.design\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ro.design\/it\/wp-json\/wp\/v2\/media\/60"}],"wp:attachment":[{"href":"https:\/\/www.ro.design\/it\/wp-json\/wp\/v2\/media?parent=859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}